{"id":87021,"date":"2025-11-04T23:28:03","date_gmt":"2025-11-05T03:28:03","guid":{"rendered":"https:\/\/www.chinesepress.com\/2025\/11\/04\/%e6%9c%9d%e9%b2%9c%e6%9c%80%e9%ab%98%e4%ba%ba%e6%b0%91%e4%bc%9a%e8%ae%ae%e5%b8%b8%e4%bb%bb%e5%a7%94%e5%91%98%e4%bc%9a%e5%89%8d%e5%a7%94%e5%91%98%e9%95%bf%e9%87%91%e6%b0%b8%e5%8d%97%e9%80%9d%e4%b8%96-2\/"},"modified":"2025-11-04T23:28:03","modified_gmt":"2025-11-05T03:28:03","slug":"%e6%9c%9d%e9%b2%9c%e6%9c%80%e9%ab%98%e4%ba%ba%e6%b0%91%e4%bc%9a%e8%ae%ae%e5%b8%b8%e4%bb%bb%e5%a7%94%e5%91%98%e4%bc%9a%e5%89%8d%e5%a7%94%e5%91%98%e9%95%bf%e9%87%91%e6%b0%b8%e5%8d%97%e9%80%9d%e4%b8%96-2","status":"publish","type":"post","link":"https:\/\/www.chinesepress.com\/pre\/archives\/87021","title":{"rendered":"\u671d\u9c9c\u6700\u9ad8\u4eba\u6c11\u4f1a\u8bae\u5e38\u4efb\u59d4\u5458\u4f1a\u524d\u59d4\u5458\u957f\u91d1\u6c38\u5357\u901d\u4e16 \u91d1\u6b63\u6069\u524d\u5f80\u540a\u5501"},"content":{"rendered":"<p>\u3000\u300011\u67084\u65e5\u7535 \u636e\u671d\u4e2d\u793e\u62a5\u9053\uff0c\u671d\u9c9c\u6700\u9ad8\u4eba\u6c11\u4f1a\u8bae\u5e38\u4efb\u59d4\u5458\u4f1a\u524d\u59d4\u5458\u957f\u91d1\u6c38\u5357\u901d\u4e16\uff0c\u671d\u9c9c\u52b3\u52a8\u515a\u603b\u4e66\u8bb0\u3001\u56fd\u52a1\u59d4\u5458\u957f\u91d1\u6b63\u606911\u67084\u65e5\u51cc\u6668\u524d\u5f80\u540a\u5501\u3002<\/p>\n<p>\u3000\u3000\u636e\u62a5\u9053\uff0c\u515a\u548c\u653f\u5e9c\u7684\u4e3b\u8981\u9886\u5bfc\u5e72\u90e8\u4e00\u540c\u524d\u5f80\u540a\u5501\u91d1\u6c38\u5357\u3002\u4ee5\u91d1\u6b63\u6069\u540d\u4e49\u656c\u732e\u7684\u82b1\u5708\u6446\u653e\u5728\u6545\u4eba\u7075\u67e9\u524d\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u3000\u300011\u67084\u65e5\u7535 \u636e\u671d\u4e2d\u793e\u62a5\u9053\uff0c\u671d\u9c9c\u6700\u9ad8\u4eba\u6c11\u4f1a\u8bae\u5e38\u4efb\u59d4\u5458\u4f1a\u524d\u59d4\u5458\u957f\u91d1\u6c38\u5357\u901d\u4e16\uff0c\u671d\u9c9c\u52b3\u52a8\u515a\u603b\u4e66\u8bb0\u3001\u56fd\u52a1\u59d4\u5458\u957f\u91d1\u6b63\u606911\u67084\u65e5\u51cc\u6668\u524d\u5f80\u540a\u5501\u3002 \u3000\u3000\u636e\u62a5\u9053\uff0c\u515a\u548c\u653f\u5e9c\u7684\u4e3b\u8981\u9886\u5bfc\u5e72\u90e8\u4e00\u540c\u524d\u5f80\u540a\u5501\u91d1\u6c38\u5357\u3002\u4ee5\u91d1\u6b63\u6069&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-87021","post","type-post","status-publish","format-standard","hentry","category-guoji"],"_links":{"self":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts\/87021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/comments?post=87021"}],"version-history":[{"count":0,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts\/87021\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/media?parent=87021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/categories?post=87021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/tags?post=87021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}