{"id":82369,"date":"2025-10-17T21:05:00","date_gmt":"2025-10-18T01:05:00","guid":{"rendered":"https:\/\/www.chinesepress.com\/?p=82369"},"modified":"2025-10-17T12:14:51","modified_gmt":"2025-10-17T16:14:51","slug":"%e6%97%a5%e6%9c%ac%e5%89%8d%e9%a6%96%e7%9b%b8%e6%9d%91%e5%b1%b1%e5%af%8c%e5%b8%82%e5%8e%bb%e4%b8%96%e4%ba%ab%e5%b9%b4101%e6%ad%b2%ef%bc%8c%e4%bb%bb%e5%85%a7%e9%a6%96%e6%ac%a1%e7%94%a8%e3%80%8c","status":"publish","type":"post","link":"https:\/\/www.chinesepress.com\/pre\/archives\/82369","title":{"rendered":"\u65e5\u672c\u524d\u9996\u76f8\u6751\u5c71\u5bcc\u5e02\u53bb\u4e16\u4eab\u5e74101\u6b72\uff0c\u4efb\u5167\u9996\u6b21\u7528\u300c\u4fb5\u7565\u300d\u8868\u8ff0\u904e\u53bb\u7684\u6230\u722d"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"531\" height=\"300\" src=\"https:\/\/www.chinesepress.com\/wp-content\/uploads\/2025\/10\/20251017143930653859911-531x300.png\" alt=\"\" class=\"wp-image-82370\" srcset=\"https:\/\/www.chinesepress.com\/pre\/wp-content\/uploads\/2025\/10\/20251017143930653859911-531x300.png 531w, https:\/\/www.chinesepress.com\/pre\/wp-content\/uploads\/2025\/10\/20251017143930653859911-400x226.png 400w, https:\/\/www.chinesepress.com\/pre\/wp-content\/uploads\/2025\/10\/20251017143930653859911.png 570w\" sizes=\"(max-width: 531px) 100vw, 531px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u3000\u64da\u65e5\u672c\u5a92\u9ad4\u5831\u9053\uff0c\u65e5\u672c\u524d\u9996\u76f8\u6751\u5c71\u5bcc\u5e02\u4eca\u5929\uff0810\u670817\u65e5\uff09\u5728\u5927\u5206\u5e02\u4e00\u5bb6\u91ab\u9662\u56e0\u8870\u8001\u53bb\u4e16\uff0c\u4eab\u5e74101\u6b72\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u3000\u6751\u5c71\u5bcc\u5e02\u65bc1924\u5e743\u67083\u65e5\u51fa\u751f\u5728\u5927\u5206\u5e02\u30021994\u5e74\u51fa\u4efb\u65e5\u672c\u9996\u76f8\uff0c2000\u5e74\u9000\u51fa\u653f\u754c\u30021995\u5e748\u670815\u65e5\uff0c\u6642\u4efb\u9996\u76f8\u7684\u6751\u5c71\u5bcc\u5e02\u767c\u8868\u8b1b\u8a71\uff0c\u627f\u8a8d\u65e5\u672c\u904e\u53bb\u5be6\u884c\u932f\u8aa4\u7684\u570b\u7b56\uff0c\u8d70\u4e86\u6230\u722d\u9053\u8def\uff0c\u300c\u5176\u6b96\u6c11\u7d71\u6cbb\u548c\u4fb5\u7565\u7d66\u8a31\u591a\u570b\u5bb6\u3001\u7279\u5225\u662f\u4e9e\u6d32\u5404\u570b\u4eba\u6c11\u5e36\u4f86\u4e86\u5de8\u5927\u7684\u640d\u5bb3\u548c\u75db\u82e6\u300d\u3002\u4ed6\u8868\u793a\uff0c\u8981\u6df1\u523b\u53cd\u7701\u6b77\u53f2\u3001\u5438\u53d6\u6b77\u53f2\u6559\u8a13\uff0c\u300c\u5fc5\u9808\u628a\u6230\u722d\u7684\u60b2\u6158\u544a\u8a34\u5e74\u9752\u4e00\u4ee3\uff0c\u4ee5\u4fbf\u4e0d\u518d\u91cd\u72af\u904e\u53bb\u7684\u932f\u8aa4\u300d\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u30002020\u5e748\u670815\u65e5\uff0c\u6751\u5c71\u5bcc\u5e02\u66fe\u901a\u904e\u5a92\u9ad4\u8868\u9054\u95dc\u65bc\u300c\u6751\u5c71\u8ac7\u8a71\u300d\u767c\u886825\u5468\u5e74\u7684\u611f\u8a00\u6307\u51fa\uff0c\u7576\u6642\u91cd\u8981\u7684\u662f\u660e\u78ba\u6b77\u53f2\u4e8b\u5be6\uff0c\u8868\u793a\u9053\u6b49\uff0c\u4e26\u8868\u660e\u4e0d\u518d\u91cd\u8907\u4fb5\u7565\u548c\u6b96\u6c11\u7d71\u6cbb\u7684\u6c7a\u5fc3\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u3000\u64da\u65e5\u672c\u5a92\u9ad4\u5831\u9053\uff0c\u65e5\u672c\u524d\u9996\u76f8\u6751\u5c71\u5bcc\u5e02\u4eca\u5929\uff0810\u670817\u65e5\uff09\u5728\u5927\u5206\u5e02\u4e00\u5bb6\u91ab\u9662\u56e0\u8870\u8001\u53bb\u4e16\uff0c\u4eab\u5e74101\u6b72\u3002 \u3000\u6751\u5c71\u5bcc\u5e02\u65bc1924\u5e743\u67083\u65e5\u51fa\u751f\u5728\u5927\u5206\u5e02\u30021994\u5e74\u51fa\u4efb\u65e5\u672c\u9996\u76f8\uff0c2000\u5e74\u9000\u51fa\u653f\u754c\u30021995\u5e748&hellip;<\/p>\n","protected":false},"author":2,"featured_media":82370,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-82369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guoji"],"_links":{"self":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts\/82369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/comments?post=82369"}],"version-history":[{"count":1,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts\/82369\/revisions"}],"predecessor-version":[{"id":82371,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts\/82369\/revisions\/82371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/media\/82370"}],"wp:attachment":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/media?parent=82369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/categories?post=82369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/tags?post=82369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}