{"id":7617,"date":"2025-01-07T12:21:55","date_gmt":"2025-01-07T17:21:55","guid":{"rendered":"https:\/\/www.chinesepress.com\/?p=7617"},"modified":"2025-01-07T12:21:56","modified_gmt":"2025-01-07T17:21:56","slug":"%e5%85%ac%e7%89%9b%e5%ae%a3%e5%b8%83%e9%80%80%e5%bd%b9%e7%be%85%e6%96%af1%e8%99%9f%e7%90%83%e8%a1%a3","status":"publish","type":"post","link":"https:\/\/www.chinesepress.com\/pre\/archives\/7617","title":{"rendered":"\u516c\u725b\u5ba3\u5e03\u9000\u5f79\u7f85\u65af1\u865f\u7403\u8863"},"content":{"rendered":"\n<p><img decoding=\"async\" src=\"https:\/\/img.takungpao.com\/2025\/0107\/2025010705015072862.jpg\"><\/p>\n\n\n\n<p>\u3000\u3000\u5716\uff1a\u7f85\u65af\uff08\u53f3\uff09\u662fNBA\u53f2\u4e0a\u6700\u5e74\u8f15\u7684\u5e38\u898f\u8cfdMVP\u3002<\/p>\n\n\n\n<p>\u3000\u3000\u64da\u4e2d\u65b0\u7db2\u5831\u9053\uff1aNBA\u7403\u968a\u516c\u725b\u767c\u5e03\u516c\u544a\u7a31\uff0c\u5c07\u57282025\u81f32026\u8cfd\u5b63\u9000\u5f79\u7f85\u65af\u7684\u7403\u8863\u865f\u78bc\u3002\u9019\u610f\u5473\u7740\uff0c\u516c\u725b\u5c07\u4e0d\u6703\u518d\u6709\u5176\u4ed6\u4efb\u4f55\u7403\u54e1\u8eab\u62ab1\u865f\u7403\u8863\u3002<\/p>\n\n\n\n<p>\u3000\u3000\u4f5c\u70baNBA\u53f2\u4e0a\u6700\u5e74\u8f15\u7684\u5e38\u898f\u8cfdMVP\uff08\u6700\u6709\u50f9\u503c\u7403\u54e1\uff09\u7372\u5f97\u8005\uff0c\u51fa\u751f\u65bc1988\u5e74\u7684\u7f85\u65af\u539f\u672c\u88ab\u5bc4\u4e88\u539a\u671b\uff0c\u4f46\u50b7\u75c5\u6467\u6bc0\u4e86\u4ed6\u7684\u8077\u696d\u751f\u6daf\u3002\u5728\u6548\u529b\u516c\u725b\u4e4b\u5f8c\uff0c\u4ed6\u66fe\u8f3e\u8f49\u7d10\u7d04\u4eba\u3001\u9a0e\u58eb\u3001\u7235\u58eb\u3001\u6728\u72fc\u3001\u6d3b\u585e\u7b49\u968a\u3002\u4eca\u5e749\u6708\uff0c\u5728\u88ab\u7070\u718a\u88c1\u6389\u5f8c\uff0c\u7f85\u65af\u96a8\u5373\u5ba3\u5e03\u9000\u5f79\u3002<\/p>\n\n\n\n<p>\u3000\u30002008\u5e74NBA\u9078\u79c0\u5927\u6703\u4e0a\uff0c\u7f85\u65af\u88ab\u516c\u725b\u5728\u9996\u8f2a\u7b2c\u4e00\u9806\u4f4d\u9078\u4e2d\u3002\u7f85\u65af\u4e5f\u6c92\u6709\u8f9c\u8ca0\u7403\u8ff7\u5011\u7684\u671f\u671b\u30022010\u81f32011\u8cfd\u5b63\uff0c\u4ed6\u4ee5\u5834\u574725\u5206\u30017.7\u6b21\u52a9\u653b\u7684\u8868\u73fe\uff0c\u7387\u968a\u53d6\u5f9762\u52dd20\u8ca0\u7684\u6230\u7e3e\uff0c\u52a0\u5195\u6b77\u53f2\u6700\u5e74\u8f15\u5e38\u898f\u8cfdMVP\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u3000\u3000\u5716\uff1a\u7f85\u65af\uff08\u53f3\uff09\u662fNBA\u53f2\u4e0a\u6700\u5e74\u8f15\u7684\u5e38\u898f\u8cfdMVP\u3002 \u3000\u3000\u64da\u4e2d\u65b0\u7db2\u5831\u9053\uff1aNBA\u7403\u968a\u516c\u725b\u767c\u5e03\u516c\u544a\u7a31\uff0c\u5c07\u57282025\u81f32026\u8cfd\u5b63\u9000\u5f79\u7f85\u65af\u7684\u7403\u8863\u865f\u78bc\u3002\u9019\u610f\u5473\u7740\uff0c\u516c\u725b\u5c07\u4e0d\u6703\u518d\u6709\u5176\u4ed6\u4efb\u4f55\u7403\u54e1\u8eab\u62ab1\u865f\u7403\u8863\u3002 \u3000\u3000&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7617","post","type-post","status-publish","format-standard","hentry","category-sports"],"_links":{"self":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts\/7617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/comments?post=7617"}],"version-history":[{"count":1,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts\/7617\/revisions"}],"predecessor-version":[{"id":7618,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/posts\/7617\/revisions\/7618"}],"wp:attachment":[{"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/media?parent=7617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/categories?post=7617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chinesepress.com\/pre\/wp-json\/wp\/v2\/tags?post=7617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}